{"id":1093,"date":"2018-03-06T18:00:24","date_gmt":"2018-03-06T18:00:24","guid":{"rendered":"https:\/\/www.justfundraising.com\/blog\/?p=1093"},"modified":"2018-03-06T18:00:24","modified_gmt":"2018-03-06T18:00:24","slug":"fundraising-for-mission-trip","status":"publish","type":"post","link":"https:\/\/www.justfundraising.com\/blog\/fundraising-for-mission-trip\/","title":{"rendered":"Fundraising For Mission Trip"},"content":{"rendered":"<div class=\"row\"  id=\"row-874138031\">\n\n\t<div id=\"col-246101943\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<p>Share And Inspire \ud83d\ude42<\/p>\n\t\t<\/div>\n\t\t\n<style>\n#col-246101943 > .col-inner {\n  margin: 0px 0px -50px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-1364750721\">\n\n\t<div id=\"col-597170811\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"social-icons share-icons share-row relative full-width text-center icon-style-fill\" ><a href=\"\/\/www.facebook.com\/sharer.php?u=https:\/\/www.justfundraising.com\/blog\/fundraising-for-mission-trip\/\" data-label=\"Facebook\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px');  return false;\" rel=\"noopener noreferrer nofollow\" target=\"_blank\" class=\"icon primary button circle tooltip facebook\" title=\"Share on Facebook\"><i class=\"icon-facebook\" ><\/i><\/a><a href=\"\/\/twitter.com\/share?url=https:\/\/www.justfundraising.com\/blog\/fundraising-for-mission-trip\/\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px');  return false;\" rel=\"noopener noreferrer nofollow\" target=\"_blank\" class=\"icon primary button circle tooltip twitter\" title=\"Share on Twitter\"><i class=\"icon-twitter\" ><\/i><\/a><a href=\"mailto:enteryour@addresshere.com?subject=Fundraising%20For%20Mission%20Trip&amp;body=Check%20this%20out:%20https:\/\/www.justfundraising.com\/blog\/fundraising-for-mission-trip\/\" rel=\"nofollow\" class=\"icon primary button circle tooltip email\" title=\"Email to a Friend\"><i class=\"icon-envelop\" ><\/i><\/a><a href=\"\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/www.justfundraising.com\/blog\/fundraising-for-mission-trip\/&amp;media=https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2018\/03\/23b-1024x1024.jpg&amp;description=Fundraising%20For%20Mission%20Trip\" onclick=\"window.open(this.href,this.title,'width=500,height=500,top=300px,left=300px');  return false;\" rel=\"noopener noreferrer nofollow\" target=\"_blank\" class=\"icon primary button circle tooltip pinterest\" title=\"Pin on Pinterest\"><i class=\"icon-pinterest\" ><\/i><\/a><\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-251250969\">\n\n\t<div id=\"col-1038194685\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p>&#8220;The first Assembly of God is selling the $10 cookie dough to help raise money for our mission trip.<span style=\"font-size: 14.4px;\">&#8220;<\/span><\/p>\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-375189830\">\n\n\n\t<div id=\"col-15519133\" class=\"col small-12 large-12\"  >\n\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"container section-title-container\" style=\"margin-bottom:9px;\"><h3 class=\"section-title section-title-normal\"><b><\/b><span class=\"section-title-main\" >Scroll Through More Posts Like This One<\/span><b><\/b><\/h3><\/div>\n\n\n  \n    <div id=\"row-1734870630\" class=\"slider slider-auto-height row-collapse slider-nav-reveal\" data-flickity-options='{\"imagesLoaded\": true, \"dragThreshold\" : 5, \"cellAlign\": \"left\",\"wrapAround\": true,\"prevNextButtons\": true,\"percentPosition\": true,\"pageDots\": false, \"rightToLeft\": false, \"autoPlay\" : 5000}'>\n\n  \t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/supporting-their-band-with-lollipops\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"school band\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/school-band.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Supporting Their Band With Lollipops<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/fundraising-to-recharter-their-pack\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"cubscouts\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/cubscouts.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Fundraising To Recharter Their Pack!<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/operation-christmas-child\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"operation christmas child\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/church.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Operation Christmas Child<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/youth-leaders-fundraising-for-scholarships\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Bowling youth leaders\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/bowling-youth-leaders.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Youth Leaders Fundraising For Scholarships<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/fundraising-to-visit-unkown-soldier\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"High school honor guard\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/12\/honor-guard.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Fundraising To Visit Tomb Of The Unknown Soldier<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/ralley-for-reese-giving-back\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"1020\" height=\"1020\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser-1024x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"Ralley for Reese\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser-1024x1024.jpg 1024w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser-300x300.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser-150x150.jpg 150w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser-768x768.jpg 768w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2022\/11\/personal-fundraiser.jpg 1080w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">Ralley For Reese &#8211; Giving Back<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/march-2020-fundraising-kick-offs\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"772\" height=\"432\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/03\/march-2020-fundraising-groups.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"March 2020 fundraising groups\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/03\/march-2020-fundraising-groups.jpg 772w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/03\/march-2020-fundraising-groups-300x168.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/03\/march-2020-fundraising-groups-768x430.jpg 768w\" sizes=\"(max-width: 772px) 100vw, 772px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">March 2020 Fundraising Kick Off&#8217;s<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t<a href=\"https:\/\/www.justfundraising.com\/blog\/february-2020-fundraising-kick-offs-2\/\" class=\"plain\">\n\t\t\t\t<div class=\"box box-overlay dark box-text-middle box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-overlay-remove image-cover\" style=\"padding-top:40%;\">\n  \t\t\t\t\t\t\t<img width=\"772\" height=\"432\" src=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/02\/february-2020-fundraiser-kick-offs.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"February 2020 fundraisers\" loading=\"lazy\" srcset=\"https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/02\/february-2020-fundraiser-kick-offs.jpg 772w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/02\/february-2020-fundraiser-kick-offs-300x168.jpg 300w, https:\/\/www.justfundraising.com\/blog\/wp-content\/uploads\/2020\/02\/february-2020-fundraiser-kick-offs-768x430.jpg 768w\" sizes=\"(max-width: 772px) 100vw, 772px\" \/>  \t\t\t\t\t\t\t<div class=\"overlay\" style=\"background-color: rgba(0, 0, 0, 0.09)\"><\/div>  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text show-on-hover hover-bounce text-center is-large\" style=\"padding:10% 0px 10% 0px;\">\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<p class=\"cat-label tag-label is-xxsmall op-7 uppercase\">\n\t\t\t\t\tThis Month's Kick-Offs \t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large \">February 2020 Fundraising Kick Off&#8217;s<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t<\/div>\n<\/div>\n\n\n\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>The first Assembly of God is selling the $10 cookie dough to help raise money for our mission<br \/>\ntrip.<\/p>\n","protected":false},"author":2,"featured_media":1094,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[352],"tags":[365,344],"yst_prominent_words":[553,489,556,514,512,518],"_links":{"self":[{"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/posts\/1093"}],"collection":[{"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/comments?post=1093"}],"version-history":[{"count":1,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/posts\/1093\/revisions"}],"predecessor-version":[{"id":1095,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/posts\/1093\/revisions\/1095"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/media\/1094"}],"wp:attachment":[{"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/media?parent=1093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/categories?post=1093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/tags?post=1093"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.justfundraising.com\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}